{"id":4739,"date":"2022-03-13T10:27:32","date_gmt":"2022-03-13T09:27:32","guid":{"rendered":"https:\/\/www.nuovafonderia.com\/?p=4739"},"modified":"2022-03-10T10:35:14","modified_gmt":"2022-03-10T09:35:14","slug":"personas-el-corazon-de-los-proyectos-y-la-innovacion","status":"publish","type":"post","link":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/","title":{"rendered":"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n"},"content":{"rendered":"<p class=\"p1\">El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad.<span class=\"Apple-converted-space\">  <\/span>Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-4739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n<\/title>\n<meta name=\"description\" content=\"El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad. Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad. Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuova Fonderia di Castenedolo\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-13T09:27:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fonderia.net\/wp-content\/uploads\/2022\/03\/persone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#\\\/schema\\\/person\\\/bf06f3868f4c0dbf203e4dd64cfc379f\"},\"headline\":\"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n\",\"datePublished\":\"2022-03-13T09:27:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fonderia.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/persone.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/\",\"url\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/\",\"name\":\"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fonderia.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/persone.jpg\",\"datePublished\":\"2022-03-13T09:27:32+00:00\",\"description\":\"El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad. Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fonderia.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/persone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fonderia.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/persone.jpg\",\"width\":1920,\"height\":1282,\"caption\":\"Piccola colata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/personas-el-corazon-de-los-proyectos-y-la-innovacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/\",\"name\":\"Fonderia di Castenedolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#organization\",\"name\":\"Fonderia di Castenedolo\",\"url\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fonderia.net\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Nuova-Fonderia-di-Castenodolo-con-sfondo-e1712146742200.png\",\"contentUrl\":\"https:\\\/\\\/www.fonderia.net\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Nuova-Fonderia-di-Castenodolo-con-sfondo-e1712146742200.png\",\"width\":75,\"height\":74,\"caption\":\"Fonderia di Castenedolo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fonderia.net\\\/es\\\/#\\\/schema\\\/person\\\/bf06f3868f4c0dbf203e4dd64cfc379f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/006128798c2211cb7d8fd8f6316aefbcb5824180c4a4e1b20801d5379d980627?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/006128798c2211cb7d8fd8f6316aefbcb5824180c4a4e1b20801d5379d980627?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/006128798c2211cb7d8fd8f6316aefbcb5824180c4a4e1b20801d5379d980627?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/fonderia.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n","description":"El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad. Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/","og_locale":"es_ES","og_type":"article","og_title":"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n","og_description":"El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad. Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.","og_url":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/","og_site_name":"Nuova Fonderia di Castenedolo","article_published_time":"2022-03-13T09:27:32+00:00","og_image":[{"width":1920,"height":1282,"url":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2022\/03\/persone.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#article","isPartOf":{"@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/"},"author":{"name":"admin","@id":"https:\/\/www.fonderia.net\/es\/#\/schema\/person\/bf06f3868f4c0dbf203e4dd64cfc379f"},"headline":"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n","datePublished":"2022-03-13T09:27:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/www.fonderia.net\/es\/#organization"},"image":{"@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2022\/03\/persone.jpg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/","url":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/","name":"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n","isPartOf":{"@id":"https:\/\/www.fonderia.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#primaryimage"},"image":{"@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2022\/03\/persone.jpg","datePublished":"2022-03-13T09:27:32+00:00","description":"El miedo a que las m\u00e1quinas sustituyan alg\u00fan d\u00eda a las personas dentro de la empresa atraviesa toda la historia de la innovaci\u00f3n tecnol\u00f3gica desde sus inicios hasta la actualidad. Sin embargo, mirando al pasado, est\u00e1 claro que las personas siempre han jugado un papel insustituible, destinado a permanecer tambi\u00e9n en el futuro. De hecho, la experiencia y la capacidad de decisi\u00f3n de las personas son indispensables incluso en los contextos m\u00e1s avanzados. Adem\u00e1s de llevar la transformaci\u00f3n digital a los procesos comerciales, el nuevo enfoque tambi\u00e9n prev\u00e9 traer una transformaci\u00f3n en el trabajo de las personas y no solo de las m\u00e1quinas.","breadcrumb":{"@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#primaryimage","url":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2022\/03\/persone.jpg","contentUrl":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2022\/03\/persone.jpg","width":1920,"height":1282,"caption":"Piccola colata"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fonderia.net\/es\/personas-el-corazon-de-los-proyectos-y-la-innovacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fonderia.net\/es\/"},{"@type":"ListItem","position":2,"name":"Personas: el coraz\u00f3n de los proyectos y la innovaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.fonderia.net\/es\/#website","url":"https:\/\/www.fonderia.net\/es\/","name":"Fonderia di Castenedolo","description":"","publisher":{"@id":"https:\/\/www.fonderia.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fonderia.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fonderia.net\/es\/#organization","name":"Fonderia di Castenedolo","url":"https:\/\/www.fonderia.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fonderia.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2024\/04\/Nuova-Fonderia-di-Castenodolo-con-sfondo-e1712146742200.png","contentUrl":"https:\/\/www.fonderia.net\/wp-content\/uploads\/2024\/04\/Nuova-Fonderia-di-Castenodolo-con-sfondo-e1712146742200.png","width":75,"height":74,"caption":"Fonderia di Castenedolo"},"image":{"@id":"https:\/\/www.fonderia.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.fonderia.net\/es\/#\/schema\/person\/bf06f3868f4c0dbf203e4dd64cfc379f","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/006128798c2211cb7d8fd8f6316aefbcb5824180c4a4e1b20801d5379d980627?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/006128798c2211cb7d8fd8f6316aefbcb5824180c4a4e1b20801d5379d980627?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/006128798c2211cb7d8fd8f6316aefbcb5824180c4a4e1b20801d5379d980627?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/fonderia.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/posts\/4739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/comments?post=4739"}],"version-history":[{"count":1,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/posts\/4739\/revisions"}],"predecessor-version":[{"id":4746,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/posts\/4739\/revisions\/4746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/media\/4744"}],"wp:attachment":[{"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/media?parent=4739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/categories?post=4739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fonderia.net\/es\/wp-json\/wp\/v2\/tags?post=4739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}